{"id":4179,"date":"2020-04-02T13:27:56","date_gmt":"2020-04-02T13:27:56","guid":{"rendered":"http:\/\/conversaspanishinstitute.com\/?p=4179"},"modified":"2020-04-20T13:37:06","modified_gmt":"2020-04-20T13:37:06","slug":"3-trucos-faciles-que-te-ayudaran-a-clavar-tu-acento-espanol","status":"publish","type":"post","link":"https:\/\/conversaspanishinstitute.com\/es\/grammar\/3-easy-hacks-to-help-you-nail-your-spanish-accent\/","title":{"rendered":"3 trucos f\u00e1ciles para perfeccionar tu acento espa\u00f1ol"},"content":{"rendered":"<!--?xml encoding=\"utf-8\" ?--><p>So you are starting to get the hang of Spanish, but your accent leaves much to be desired? Don\u2019t worry!\u00a0<\/p>\n\n\n\n<p>Es <a href=\"https:\/\/www.linguisticsociety.org\/content\/why-do-some-people-have-accent\">perfectamente normal<\/a> for native English speakers to struggle a bit with their accent, especially if you haven\u2019t had much chance to practice your Spanish skills in the real world.\u00a0<\/p>\n\n\n\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/conversaspanishinstitute.com\/es\/onlineactivities\/verb-conjugations\/\" class=\"template-4\"><img width=\"250\" height=\"159\" src=\"https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2018\/03\/CONVERSA-CONJUGATE-SPANISH-VERBS-IN-PRESENT.png\" class=\"alignleft wp-post-image\" alt=\"CONVERSA CONJUGA VERBOS ESPA\u00d1OLES EN PRESENTE\" srcset=\"https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2018\/03\/CONVERSA-CONJUGATE-SPANISH-VERBS-IN-PRESENT.png 825w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2018\/03\/CONVERSA-CONJUGATE-SPANISH-VERBS-IN-PRESENT-600x382.png 600w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2018\/03\/CONVERSA-CONJUGATE-SPANISH-VERBS-IN-PRESENT-300x191.png 300w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2018\/03\/CONVERSA-CONJUGATE-SPANISH-VERBS-IN-PRESENT-768x489.png 768w\" sizes=\"(max-width: 250px) 100vw, 250px\"><div class=\"postTitle\"><span><strong>Leer m\u00e1s<\/strong>Actividad en l\u00ednea: Conjugar verbos espa\u00f1oles en presente<\/span><\/div><\/a><\/div><p>Don\u2019t sweat it though. These three simple hacks will have you speaking Spanish like a native in no-time.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. Memoriza esos sonidos voc\u00e1licos<\/h2>\n\n\n\n<p>Una v\u00eda r\u00e1pida para aprender a hablar espa\u00f1ol correctamente es asegurarte de que entiendes bien las vocales. Despu\u00e9s de todo, cualquiera que haya visto alguna vez La Rueda de la Fortuna sabr\u00e1 que en las palabras suele haber muchas m\u00e1s vocales que otras letras.\u00a0<\/p>\n\n\n\n<div class=\"internal-linking-related-contents-pro\"><a href=\"https:\/\/conversaspanishinstitute.com\/es\/onlineactivities\/plural-noun\/\" class=\"template-4\"><img width=\"250\" height=\"159\" src=\"https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2019\/04\/CONVERSA-Almost-as-simple-as-adding-s.png\" class=\"alignleft wp-post-image\" alt=\"CONVERSA Casi tan sencillo como a\u00f1adir -s\" srcset=\"https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2019\/04\/CONVERSA-Almost-as-simple-as-adding-s.png 825w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2019\/04\/CONVERSA-Almost-as-simple-as-adding-s-600x382.png 600w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2019\/04\/CONVERSA-Almost-as-simple-as-adding-s-300x191.png 300w, https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2019\/04\/CONVERSA-Almost-as-simple-as-adding-s-768x489.png 768w\" sizes=\"(max-width: 250px) 100vw, 250px\"><div class=\"postTitle\"><span><strong>Leer m\u00e1s<\/strong>El plural de los sustantivos en espa\u00f1ol: Lo fundamental<\/span><\/div><\/a><\/div><p>Mejor a\u00fan, los sonidos voc\u00e1licos son relativamente <a href=\"http:\/\/esl.fis.edu\/grammar\/langdiff\/spanish.htm\">descomplicado en espa\u00f1ol<\/a> compared to English in that vowel makes only one sound. So why not \u2018buy a vowel\u2019 and supercharge your Spanish accent?<\/p>\n\n\n\n<p>Aqu\u00ed tienes un r\u00e1pido desglose de c\u00f3mo deben sonar todos los sonidos voc\u00e1licos.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Di <strong>A<\/strong> like the\u00a0 \u2018a\u2019 in \u2018<em>padre<\/em>\u2019<\/li><li>Di <strong>E <\/strong>like the \u2018e\u2019 in \u2018<em>alimentado<\/em>\u2018<\/li><li>Di<strong> E<\/strong> like the \u2018ee\u2019 in \u2018<em>bee\u2019<\/em><\/li><li>Di <strong>O<\/strong> like the \u2018o\u2019 in \u2018<em>no<\/em>\u2018<\/li><li>Di<strong> U<\/strong> like the \u2018oo\u2019 in \u2018<em>demasiado<\/em>\u2018<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">2. Aprende cu\u00e1ndo enlazar palabras<\/h2>\n\n\n\n<p>Si en general hay algo que separa al hablante nativo de espa\u00f1ol del que no lo es, es conocer y comprender el sutil matiz de cu\u00e1ndo enlazar las palabras para crear una mezcla que a menudo suena como una sola palabra larga.\u00a0<\/p>\n\n\n\n<p>Cuando comprendas las reglas de esta valiosa habilidad por dentro y por fuera, no s\u00f3lo podr\u00e1s hablar mejor, sino que tambi\u00e9n mejorar\u00e1s tu propia comprensi\u00f3n. Esto se debe a que, cuando aprendas a aprovechar los matices m\u00e1s sutiles de los patrones del habla, estar\u00e1s mejor equipado para entender tambi\u00e9n lo que dicen los dem\u00e1s.\u00a0<\/p>\n\n\n\n<p>Teniendo esto en cuenta, he aqu\u00ed los tres casos generales en los que los hablantes pro-espa\u00f1ol enlazar\u00e1n sus palabras.\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Cuando la \u00faltima letra de la primera palabra es una consonante y la primera letra de la palabra siguiente es una vocal<\/li><li>Cuando la \u00faltima letra de la primera palabra es la misma que la primera letra de la palabra siguiente<\/li><li>Cuando la \u00faltima letra de la primera palabra y la primera letra de la palabra siguiente son vocales<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">3. Don\u2019t Leave Out the Accents<\/h2>\n\n\n\n<p>La pronunciaci\u00f3n espa\u00f1ola sigue un ritmo familiar que casi siempre es el mismo. Esto significa que, como norma general, debes intentar poner el acento en la pen\u00faltima s\u00edlaba de una palabra.<\/p>\n\n\n\n<p>Sin embargo, algunas palabras se salen del molde, y sabr\u00e1s que te has encontrado con una cuando veas un acento, que b\u00e1sicamente te dice exactamente d\u00f3nde poner el acento en su lugar.\u00a0<\/p>\n\n\n\n<p><em>Ver\u00e1s. F\u00e1cil, \u00bfverdad?<\/em><\/p>\n\n\n\n<p>Claro que la pr\u00e1ctica ayuda, pero si buscas una forma mejor de llevar tus conocimientos de espa\u00f1ol al siguiente nivel, no busques m\u00e1s que el <strong>Conversa Spanish Institute<\/strong>.\u00a0<\/p>\n\n\n\n<p>Nuestro programa integral de aprendizaje de idiomas, basado en procesos, aprovecha esa parte de tu mente que es responsable de la forma en que la gente aprende. B\u00e1sicamente, nuestros m\u00f3dulos, \u00fanicos en su g\u00e9nero, dan a tu cerebro un superimpulso canalizando el poder de la conciencia meditativa para aumentar tu concentraci\u00f3n e incrementar tu potencial general de aprendizaje. Ahora t\u00fa tambi\u00e9n puedes entender por qu\u00e9 algunas personas parecen aprender idiomas como si nada. Por eso queremos darte las claves para desbloquear todo tu poder de aprendizaje de idiomas. <a href=\"http:\/\/conversaspanishinstitute.com\/es\/\">M\u00e1s informaci\u00f3n<\/a> hoy aqu\u00ed.\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>So you are starting to get the hang of Spanish, but your accent leaves much to be desired? Don\u2019t worry!\u00a0 It is perfectly normal for native English speakers to struggle a bit with their accent, especially if you haven\u2019t had much chance to practice your Spanish skills in the real world.\u00a0 Leer m\u00e1sOnline Activity: Conjugate [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4180,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[141,122,30,87,89],"tags":[48,88],"class_list":["post-4179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-education","category-grammar","category-language","category-learning","tag-learn-spanish","tag-learn-to-speak-spanish"],"acf":[],"jetpack_featured_media_url":"https:\/\/conversaspanishinstitute.com\/wp-content\/uploads\/2020\/04\/3-Easy-Hacks-to-Help-You-Nail-Your-Spanish-Accent.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/posts\/4179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/comments?post=4179"}],"version-history":[{"count":0,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/posts\/4179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/media\/4180"}],"wp:attachment":[{"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/media?parent=4179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/categories?post=4179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversaspanishinstitute.com\/es\/wp-json\/wp\/v2\/tags?post=4179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}